{"id":1597,"date":"2023-06-06T11:04:30","date_gmt":"2023-06-06T10:04:30","guid":{"rendered":"https:\/\/testosteron-eu.com\/wishlist\/"},"modified":"2024-10-10T22:59:16","modified_gmt":"2024-10-10T21:59:16","slug":"lista-de-deseos","status":"publish","type":"page","link":"https:\/\/testosteron-eu.com\/es\/lista-de-deseos\/","title":{"rendered":"Lista de deseos"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column]\t\t\n\t\t\n\t\t<div class=\"\">\n\t\t\t\t\t\t<div class=\"wd-wishlist-content\">\n\t\t\t\t\t\t\t\t\t\t\t\n\t\t<p class=\"wd-empty-wishlist wd-empty-page\">\n\t\t\tEsta lista de deseos est\u00e1 vac\u00eda.\t\t<\/p>\n\n\t\t\t\t\t<div class=\"wd-empty-page-text\">\n\t\t\t\tA\u00fan no tienes productos en tu lista de deseos. Encontrar\u00e1s muchos productos interesantes en nuestra p\u00e1gina \"Tienda\".\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\t\t\t<p class=\"return-to-shop\">\n\t\t\t\t<a class=\"button\" href=\"https:\/\/testosteron-eu.com\/es\/tienda\/\">\n\t\t\t\t\tVolver a la tienda\t\t\t\t<\/a>\n\t\t\t<\/p>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1597","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/testosteron-eu.com\/es\/wp-json\/wp\/v2\/pages\/1597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/testosteron-eu.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/testosteron-eu.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/testosteron-eu.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/testosteron-eu.com\/es\/wp-json\/wp\/v2\/comments?post=1597"}],"version-history":[{"count":1,"href":"https:\/\/testosteron-eu.com\/es\/wp-json\/wp\/v2\/pages\/1597\/revisions"}],"predecessor-version":[{"id":1601,"href":"https:\/\/testosteron-eu.com\/es\/wp-json\/wp\/v2\/pages\/1597\/revisions\/1601"}],"wp:attachment":[{"href":"https:\/\/testosteron-eu.com\/es\/wp-json\/wp\/v2\/media?parent=1597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}